{"id":19137,"date":"2023-09-08T12:30:47","date_gmt":"2023-09-08T10:30:47","guid":{"rendered":"https:\/\/www.visitkranj.com\/?post_type=izbrani-dogodki&#038;p=19137"},"modified":"2026-07-06T09:00:30","modified_gmt":"2026-07-06T07:00:30","slug":"e-venerdi","status":"publish","type":"izbrani-dogodki","link":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/","title":{"rendered":"\u00c8 venerd\u00ec!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19137\" class=\"elementor elementor-19137 elementor-3858\" data-elementor-post-type=\"izbrani-dogodki\">\n\t\t\t\t<div class=\"elementor-element elementor-element-407cc94e e-flex e-con-boxed e-con e-parent\" data-id=\"407cc94e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7daddccc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"7daddccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00c8 VENERD\u00cc!<br \/><span style=\"color: #808080;\">maggio &#8211; settembre 2026<\/span><\/h2><h3>\ud83c\udf27\ufe0f Vi informiamo che, a causa delle previsioni meteorologiche sfavorevoli per domani, 6 giugno 2026, \u00c8 venerd\u00ec! \u00e8 purtroppo annullato.<\/h3><h3>Grazie per la comprensione.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0355d5d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"0355d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00c8 VENERD\u00cc!<br \/><span style=\"color: #808080;\">12 giugno 2026 | 17.00\u201322.00<\/span><\/h2><p>\u00c8 venerd\u00ec! torna ancora una volta nel cuore di Kranj con un rilassato appuntamento del venerd\u00ec. Oltre a ottimo cibo e bevande, i visitatori potranno godersi la musica dal vivo del <strong>sassofonista Jani \u0160epetavec<\/strong> e di un <strong>DJ<\/strong>, accompagnata da un ricco programma di attivit\u00e0.<\/p><p>Ad attendervi ci sar\u00e0 un\u2019ampia offerta <strong>gastronomica<\/strong> con <strong>street food italiano<\/strong>, <strong>pad thai<\/strong>, <strong>dolci<\/strong> da forno, <strong>cocktail<\/strong>, <strong>bevande<\/strong> analcoliche e <strong>birra<\/strong> artigianale.<\/p><p>Alle ore <strong>19.00<\/strong>, in <strong>Piazza Glavni trg<\/strong>, si terr\u00e0 la <strong>Sfilata di moda estiva<\/strong>, con la partecipazione di boutique locali, stilisti e marchi di abbigliamento.<\/p><p>Saranno inoltre presenti gli imprenditori della <strong>LIFT Academy<\/strong> di <strong>Kova\u010dnica<\/strong>, che presenteranno i loro prodotti innovativi e le loro storie, tra cui <strong>POP Matcha<\/strong>, <strong>Hormonelle<\/strong> e <strong>MikeaPets<\/strong>.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1009311\" src=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/06\/Kr-petek-je_12.6.2026_Visit-Kranj.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/06\/Kr-petek-je_12.6.2026_Visit-Kranj.jpg 1200w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/06\/Kr-petek-je_12.6.2026_Visit-Kranj-300x157.jpg 300w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/06\/Kr-petek-je_12.6.2026_Visit-Kranj-1024x536.jpg 1024w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/06\/Kr-petek-je_12.6.2026_Visit-Kranj-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-043dcd5 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"043dcd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"68\" src=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/01\/Visit-Kranj_cgp_divider_linije_v2-300x68.png\" class=\"attachment-medium size-medium wp-image-993998\" alt=\"\" srcset=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/01\/Visit-Kranj_cgp_divider_linije_v2-300x68.png 300w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/01\/Visit-Kranj_cgp_divider_linije_v2-768x173.png 768w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/01\/Visit-Kranj_cgp_divider_linije_v2.png 852w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b70bf45 elementor-widget elementor-widget-text-editor\" data-id=\"b70bf45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00c8 VENERD\u00cc!<br \/><span style=\"color: #808080;\">maggio &#8211; settembre 2026<\/span><\/h2><p>Ogni venerd\u00ec sulla piazza principale di Kranj, accanto alla fontana, si svolge un rilassante appuntamento con cibi e bevande, che rappresenta il giusto preludio a un fine settimana spensierato!<\/p><p>Dal <strong>maggio <\/strong>al<strong>\u00a0settembre<\/strong>, ogni venerd\u00ec pomeriggio (tra le 17 e le 22) a Kranje si svolge la manifestazione Kr&#8217; petek je! (E&#8217; venerd\u00ec!), a pochi passi dalla fontana sulla piazza principale della citt\u00e0, dove i residenti e chiunque ne abbia voglia potranno ritrovarsi per fare due chiacchiere e trascorrere qualche ora in rilassatezza, davanti a del buon cibo e a bevande fresche.<\/p><blockquote><p>Le date degli appuntamenti di quest&#8217;anno sono: 5. 6., 12. 6., 19. 6., 26. 6., 3. 7., <strong>10. 7.<\/strong>, 17. 7., 7. 8., 14. 8, 21. 8., 28. 8. in 4. 9. 2026, e gli eventi si svolgeranno dalle <strong>17:00 alle 22:00<\/strong>.<\/p><\/blockquote><p><img decoding=\"async\" class=\"alignnone size-full wp-image-1012236\" src=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/07\/Kr-petek-je_10.7.2026_Visit-Kranj.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/07\/Kr-petek-je_10.7.2026_Visit-Kranj.jpg 1200w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/07\/Kr-petek-je_10.7.2026_Visit-Kranj-300x157.jpg 300w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/07\/Kr-petek-je_10.7.2026_Visit-Kranj-1024x536.jpg 1024w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2026\/07\/Kr-petek-je_10.7.2026_Visit-Kranj-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p><p>Oltre al piacere culinaria, accompagnato da bevande di ogni tipo, sar\u00e0 possibile trovare anche rivenditori di frutta fresca e di stagione, sempre di ottima qualit\u00e0, insieme a prodotti dell&#8217;orto locale. Non mancher\u00e0 la musica, con diversi compositori e suonatori che contribuiranno a creare una piacevole atmosfera e ci culleranno fino a tarda sera con i loro ritmi.<\/p><blockquote><p>Guarda <a href=\"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/fotografie\"><strong>QUI<\/strong><\/a> la galleria fotografica delle passate edizioni.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32eed4b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"32eed4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00c8 VENERD\u00cc!<br \/><span style=\"color: #808080;\">maggio &#8211; settembre 2025<\/span><\/h2><p>Ogni venerd\u00ec sulla piazza principale di Kranj, accanto alla fontana, si svolge un rilassante appuntamento con cibi e bevande, che rappresenta il giusto preludio a un fine settimana spensierato!<\/p><p>Dal <strong>maggio <\/strong>al<strong>\u00a0settembre<\/strong>, ogni venerd\u00ec pomeriggio (tra le <strong>17 e le 22<\/strong>) a Kranje si svolge la manifestazione Kr&#8217; petek je! (E&#8217; venerd\u00ec!), a pochi passi dalla fontana sulla piazza principale della citt\u00e0, dove i residenti e chiunque ne abbia voglia potranno ritrovarsi per fare due chiacchiere e trascorrere qualche ora in rilassatezza, davanti a del buon cibo e a bevande fresche.<\/p><blockquote><p>Le date degli appuntamenti di quest&#8217;anno sono: 23. 5., 30. 5., 6. 6., 13. 6., 20. 6., 27. 6., 4. 7., 11. 7., 18. 7., 8. 8., 15. 8., 22. 8.,<strong> 29. 8.<\/strong> e <strong>5. 9. 2025<\/strong>, e gli eventi si svolgeranno dalle <strong>17:00 alle 22:00<\/strong>.<\/p><\/blockquote><p>Oltre al piacere culinaria, accompagnato da bevande di ogni tipo, sar\u00e0 possibile trovare anche rivenditori di frutta fresca e di stagione, sempre di ottima qualit\u00e0, insieme a prodotti dell&#8217;orto locale. Non mancher\u00e0 la musica, con diversi compositori e suonatori che contribuiranno a creare una piacevole atmosfera e ci culleranno fino a tarda sera con i loro ritmi.<\/p><blockquote><p>Guarda <a href=\"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/fotografie\"><strong>QUI<\/strong><\/a> la galleria fotografica delle passate edizioni.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0166c7d elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"0166c7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;autoplay_speed&quot;:3500,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6907\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6907.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6802\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6802.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6768\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6768.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6879\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6879.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_7035\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_7035.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_7094\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_7094.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_0995\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_0995.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_0886\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_0886.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_1235\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_1235.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_1363\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_1363.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Precedente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Successivo\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Slides Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6907\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6907.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6802\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6802.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6768\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6768.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_6879\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_6879.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_7035\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_7035.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_7094\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_7094.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_0995\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_0995.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_0886\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_0886.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_1235\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_1235.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"PRO_1363\" style=\"background-image: url(&#039;https:\/\/www.visitkranj.com\/wp-content\/uploads\/2025\/07\/PRO_1363.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-071881c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"071881c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0328f01 elementor-widget elementor-widget-text-editor\" data-id=\"0328f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #c61647;\">\u2192<\/span> VIDEO<\/strong>:<\/p><p><iframe title=\"Kr&#039; petek je!\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/_YLjubn98DA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6bf18 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"5b6bf18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00c8 VENERD\u00cc!<br \/><span style=\"color: #808080;\">maggio &#8211; settembre 2025<\/span><\/h2><p><em>Maggiori informazioni sull\u2019evento del 2025 saranno pubblicate nei prossimi mesi.<\/em><\/p><hr \/><p>Ogni venerd\u00ec sulla piazza principale di Kranj, accanto alla fontana, si svolge un rilassante appuntamento con cibi e bevande, che rappresenta il giusto preludio a un fine settimana spensierato!<\/p><p>Dal <strong>31 maggio al 6 settembre<\/strong>, ogni venerd\u00ec pomeriggio (tra le <strong>17 e le 22<\/strong>) a Kranje si svolge la manifestazione Kr&#8217; petek je! (E&#8217; venerd\u00ec!), a pochi passi dalla fontana sulla piazza principale della citt\u00e0, dove i residenti e chiunque ne abbia voglia potranno ritrovarsi per fare due chiacchiere e trascorrere qualche ora in rilassatezza, davanti a del buon cibo e a bevande fresche.<\/p><blockquote><p>Le date degli appuntamenti di quest&#8217;anno sono: 31.5., 14.6., 21.6., 28.6., 5.7., 12.7., 19.7., 9.8., 16.8., 23 agosto e <strong>6 settembre<\/strong>, e gli eventi si svolgeranno dalle <strong>17:00 alle 22:00<\/strong>.<\/p><\/blockquote><p>Oltre al piacere culinaria, accompagnato da bevande di ogni tipo, sar\u00e0 possibile trovare anche rivenditori di frutta fresca e di stagione, sempre di ottima qualit\u00e0, insieme a prodotti dell&#8217;orto locale. Non mancher\u00e0 la musica, con diversi compositori e suonatori che contribuiranno a creare una piacevole atmosfera e ci culleranno fino a tarda sera con i loro ritmi.<\/p><blockquote><p>Guarda <a href=\"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/fotografie\"><strong>QUI<\/strong><\/a> la galleria fotografica delle passate edizioni.<\/p><\/blockquote><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-347743\" src=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2024\/02\/Kr-petek-je-2023_Visit-Kranj_4.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2024\/02\/Kr-petek-je-2023_Visit-Kranj_4.jpg 1500w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2024\/02\/Kr-petek-je-2023_Visit-Kranj_4-300x200.jpg 300w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2024\/02\/Kr-petek-je-2023_Visit-Kranj_4-1024x683.jpg 1024w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2024\/02\/Kr-petek-je-2023_Visit-Kranj_4-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05fad6d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"05fad6d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c536ea7 elementor-widget elementor-widget-text-editor\" data-id=\"c536ea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00c8 VENERD\u00cc!<br \/><span style=\"color: #808080;\">2 giugno &#8211; 8 settembre 2023 \u250216.00-21.00<\/span><\/h2><p>Da\u00a0<strong>2 giugno a 8 settembre<\/strong>, i venerd\u00ec pomeriggio a Kranj sono allietati dall&#8217;appuntamento eno-gastronomico Kr &#8216;petek je! (\u00c8 venerd\u00ec!). L&#8217;evento si svolge nella\u00a0<strong>piazza principale vicino alla fontana<\/strong>, dove di solito ogni venerd\u00ec, dopo il lavoro, gli abitanti di Kranj si riuniscono per scoprire e gustare una variet\u00e0 di\u00a0<strong>prodotti di qualit\u00e0, freschi e di stagione.<\/strong><\/p><p>D&#8217;estate invece l&#8217;evento \u00c8 venerd\u00ec! metter\u00e0 in mostra deliziosa\u00a0<strong>frutta di stagione e prodotti locali dell&#8217;orto<\/strong>. Per rendere l&#8217;offerta ancora pi\u00f9 variegata, i produttori locali saranno affiancati da coltivatori di altre parti della Slovenia. Oltre alle bancarelle ben fornite, da tenere sempre in considerazione l&#8217;offerta gastronomica nel cuore della citt\u00e0, dove anche i buongustai pi\u00f9 esigenti potranno divertirsi.<\/p><p><strong>Inoltre, associazioni culturali e gruppi folcloristici<\/strong>\u00a0si occuperanno di creare un&#8217;atmosfera conviviale e allegra, mentre la sera si alterneranno\u00a0<strong>vari maestri della musica<\/strong>\u00a0a cullare i partecipanti.<\/p><blockquote><h4><strong>Unisciti a noi sulla piazza principale di Kranj per un incontro rilassato con cibo e bevande e per dare inizio al weekend in modo spensierato!<\/strong><\/h4><\/blockquote><p>Poich\u00e9 vogliamo offrire alla gente di Kranj solo il meglio e fornire una selezione diversificata, invitiamo anche tutti i\u00a0<strong>coltivatori locali, gli agricoltori e i fornitori di servizi di catering a unirsi a noi<\/strong>. Per ulteriori informazioni scriveteci a\u00a0<strong>info@visitkranj.si<\/strong>\u00a0.<\/p><p>\u2022 Guarda\u00a0<a href=\"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/fotografie\"><strong>QUI<\/strong><\/a>\u00a0la galleria fotografica delle passate edizioni.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13870 size-full\" src=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/05\/PresernoPoletje-Bener-1600x200-II.jpg\" alt=\"\" width=\"1600\" height=\"200\" srcset=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/05\/PresernoPoletje-Bener-1600x200-II.jpg 1600w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/05\/PresernoPoletje-Bener-1600x200-II-300x38.jpg 300w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/05\/PresernoPoletje-Bener-1600x200-II-1024x128.jpg 1024w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/05\/PresernoPoletje-Bener-1600x200-II-768x96.jpg 768w, https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/05\/PresernoPoletje-Bener-1600x200-II-1536x192.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c8 VENERD\u00cc!maggio &#8211; settembre 2026 \ud83c\udf27\ufe0f Vi informiamo che, a causa delle previsioni meteorologiche sfavorevoli per domani, 6 giugno 2026, \u00c8 venerd\u00ec! \u00e8 purtroppo annullato. Grazie per la comprensione. \u00c8 VENERD\u00cc!12 giugno 2026 | 17.00\u201322.00 \u00c8 venerd\u00ec! torna ancora una volta nel cuore di Kranj con un rilassato appuntamento del venerd\u00ec. Oltre a ottimo cibo [&hellip;]<\/p>\n","protected":false},"featured_media":158971,"parent":0,"menu_order":0,"template":"","class_list":["post-19137","izbrani-dogodki","type-izbrani-dogodki","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c8 venerd\u00ec! - Visit Kranj<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c8 venerd\u00ec! - Visit Kranj\" \/>\n<meta property=\"og:description\" content=\"\u00c8 VENERD\u00cc!maggio &#8211; settembre 2026 \ud83c\udf27\ufe0f Vi informiamo che, a causa delle previsioni meteorologiche sfavorevoli per domani, 6 giugno 2026, \u00c8 venerd\u00ec! \u00e8 purtroppo annullato. Grazie per la comprensione. \u00c8 VENERD\u00cc!12 giugno 2026 | 17.00\u201322.00 \u00c8 venerd\u00ec! torna ancora una volta nel cuore di Kranj con un rilassato appuntamento del venerd\u00ec. Oltre a ottimo cibo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Kranj\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitKranj\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T07:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/07\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/\",\"url\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/\",\"name\":\"\u00c8 venerd\u00ec! - Visit Kranj\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitkranj.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg\",\"datePublished\":\"2023-09-08T10:30:47+00:00\",\"dateModified\":\"2026-07-06T07:00:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitkranj.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitkranj.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg\",\"width\":1800,\"height\":812},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/e-venerdi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inizio\",\"item\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi selezionati\",\"item\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/eventi-selezionati\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c8 venerd\u00ec!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/\",\"name\":\"Visit Kranj\",\"description\":\"Uradna spletna stran turizma Kranj\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/#organization\",\"name\":\"Zavod za turizem in kulturo Kranj\",\"url\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visitkranj.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_menu_small.png\",\"contentUrl\":\"https:\\\/\\\/www.visitkranj.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_menu_small.png\",\"width\":142,\"height\":142,\"caption\":\"Zavod za turizem in kulturo Kranj\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitkranj.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VisitKranj\\\/\",\"https:\\\/\\\/www.instagram.com\\\/visitkranj\\\/\",\"https:\\\/\\\/www.tripadvisor.com\\\/Attraction_Review-g644300-d7289577-Reviews-Tourist_Information_Centre_Kranj_House-Kranj_Upper_Carniola_Region.html\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c8 venerd\u00ec! - Visit Kranj","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/","og_locale":"it_IT","og_type":"article","og_title":"\u00c8 venerd\u00ec! - Visit Kranj","og_description":"\u00c8 VENERD\u00cc!maggio &#8211; settembre 2026 \ud83c\udf27\ufe0f Vi informiamo che, a causa delle previsioni meteorologiche sfavorevoli per domani, 6 giugno 2026, \u00c8 venerd\u00ec! \u00e8 purtroppo annullato. Grazie per la comprensione. \u00c8 VENERD\u00cc!12 giugno 2026 | 17.00\u201322.00 \u00c8 venerd\u00ec! torna ancora una volta nel cuore di Kranj con un rilassato appuntamento del venerd\u00ec. Oltre a ottimo cibo [&hellip;]","og_url":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/","og_site_name":"Visit Kranj","article_publisher":"https:\/\/www.facebook.com\/VisitKranj\/","article_modified_time":"2026-07-06T07:00:30+00:00","og_image":[{"width":1800,"height":812,"url":"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/07\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/","url":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/","name":"\u00c8 venerd\u00ec! - Visit Kranj","isPartOf":{"@id":"https:\/\/www.visitkranj.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/#primaryimage"},"image":{"@id":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/07\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg","datePublished":"2023-09-08T10:30:47+00:00","dateModified":"2026-07-06T07:00:30+00:00","breadcrumb":{"@id":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/#primaryimage","url":"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/07\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg","contentUrl":"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2023\/07\/Kr-petek-je-2023_Visit-Kranj_hero-banner.jpg","width":1800,"height":812},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/e-venerdi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inizio","item":"https:\/\/www.visitkranj.com\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi selezionati","item":"https:\/\/www.visitkranj.com\/it\/eventi-selezionati\/"},{"@type":"ListItem","position":3,"name":"\u00c8 venerd\u00ec!"}]},{"@type":"WebSite","@id":"https:\/\/www.visitkranj.com\/it\/#website","url":"https:\/\/www.visitkranj.com\/it\/","name":"Visit Kranj","description":"Uradna spletna stran turizma Kranj","publisher":{"@id":"https:\/\/www.visitkranj.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitkranj.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.visitkranj.com\/it\/#organization","name":"Zavod za turizem in kulturo Kranj","url":"https:\/\/www.visitkranj.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.visitkranj.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2022\/11\/logo_menu_small.png","contentUrl":"https:\/\/www.visitkranj.com\/wp-content\/uploads\/2022\/11\/logo_menu_small.png","width":142,"height":142,"caption":"Zavod za turizem in kulturo Kranj"},"image":{"@id":"https:\/\/www.visitkranj.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VisitKranj\/","https:\/\/www.instagram.com\/visitkranj\/","https:\/\/www.tripadvisor.com\/Attraction_Review-g644300-d7289577-Reviews-Tourist_Information_Centre_Kranj_House-Kranj_Upper_Carniola_Region.html"]}]}},"_links":{"self":[{"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/izbrani-dogodki\/19137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/izbrani-dogodki"}],"about":[{"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/types\/izbrani-dogodki"}],"version-history":[{"count":81,"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/izbrani-dogodki\/19137\/revisions"}],"predecessor-version":[{"id":1012251,"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/izbrani-dogodki\/19137\/revisions\/1012251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/media\/158971"}],"wp:attachment":[{"href":"https:\/\/www.visitkranj.com\/it\/wp-json\/wp\/v2\/media?parent=19137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}